{"id":116067,"date":"2025-08-25T09:10:48","date_gmt":"2025-08-25T12:10:48","guid":{"rendered":"https:\/\/cbl.org.br\/?p=116067"},"modified":"2025-08-25T09:10:48","modified_gmt":"2025-08-25T12:10:48","slug":"debates-sobre-inovacao-aquisicoes-editoriais-e-politicas-publicas-marcam-o-4o-encontro-de-editores-livreiros-distribuidores-e-graficos","status":"publish","type":"post","link":"https:\/\/cbltestlnx.azurewebsites.net\/en\/2025\/08\/debates-sobre-inovacao-aquisicoes-editoriais-e-politicas-publicas-marcam-o-4o-encontro-de-editores-livreiros-distribuidores-e-graficos\/","title":{"rendered":"Debates sobre inova\u00e7\u00e3o, aquisi\u00e7\u00f5es editoriais  e pol\u00edticas p\u00fablicas marcam o 4\u00ba Encontro de Editores, Livreiros, Distribuidores e Gr\u00e1ficos"},"content":{"rendered":"<p><em>Com 23 mesas e mais de 300 participantes, evento se consolida como f\u00f3rum estrat\u00e9gico para debater a cadeia do livro no Brasil<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Com a participa\u00e7\u00e3o de mais de 300 profissionais do setor, 9 expositores, 18 patrocinadores, 23 mesas e um total de 67 palestrantes, incluindo dois convidados internacionais, a 4\u00aa edi\u00e7\u00e3o do Encontro de Editores, Livreiros, Distribuidores e Gr\u00e1ficos confirmou-se como um dos principais f\u00f3runs estrat\u00e9gicos da cadeia do livro no Brasil. Realizado pela C\u00e2mara Brasileira do Livro (CBL), no Guaruj\u00e1 (SP), o evento chegou ao terceiro dia reunindo debates sobre inova\u00e7\u00e3o, aquisi\u00e7\u00f5es editoriais, fortalecimento de autores nacionais, pr\u00e1ticas de ESG e as perspectivas do Plano Nacional do Livro e Leitura (PNLL).<\/p>\n<p>\u201cOs resultados desta edi\u00e7\u00e3o mostram a for\u00e7a do nosso setor quando se re\u00fane para trocar experi\u00eancias e pensar o futuro em conjunto. Reunir mais de 300 profissionais, dezenas de mesas de debate e nomes nacionais e internacionais \u00e9 a prova de que o Encontro se consolidou como um espa\u00e7o estrat\u00e9gico para fortalecer a cadeia do livro e apontar caminhos para os pr\u00f3ximos anos\u201d, afirma <strong>Sevani Matos<\/strong>, presidente da C\u00e2mara Brasileira do Livro (CBL).<\/p>\n<p>Entre os destaques dos dias 21 e 22 de agosto esteve a participa\u00e7\u00e3o do americano Andy Hunter, fundador e CEO da Bookshop.org, entrevistado pela jornalista Raquel Cozer. Hunter refor\u00e7ou o prop\u00f3sito da plataforma de apoiar livrarias independentes, afirmando que n\u00e3o busca competir com a Amazon, mas garantir que os leitores tenham acesso aos livros. Segundo ele, a experi\u00eancia de frequentar livrarias na inf\u00e2ncia marca os leitores e deve ser preservada, ainda que isso represente abrir m\u00e3o de alguns d\u00f3lares a mais. O executivo tamb\u00e9m revelou planos de internacionaliza\u00e7\u00e3o e destacou a meta de expandir a atua\u00e7\u00e3o da Bookshop com ebooks e audiobooks no Brasil.<\/p>\n<p>Na sequ\u00eancia, a mesa \u201cComo escolher um livro: bastidores das aquisi\u00e7\u00f5es e tend\u00eancias no mercado editorial\u201d, mediada por Rodrigo Casarin (P\u00e1gina Cinco\/UOL), reuniu Flor\u00eancia Ferrari (Ubu Editora), Yasmin Santos (Companhia das Letras), Tamires Von Atzingen (VR Editora) e Rosely Boschini (Editora Gente). Boschini destacou que o foco deve estar sempre no leitor, observando dores, alegrias e tend\u00eancias, como a crescente relev\u00e2ncia da sa\u00fade mental. Yasmin Santos defendeu a import\u00e2ncia de olhar mais de perto para os debates da Am\u00e9rica Latina e apontou o redescobrimento dos cl\u00e1ssicos como movimento relevante. J\u00e1 Tamires Von Atzingen ressaltou a necessidade de conhecer profundamente o p\u00fablico-alvo, utilizando as observa\u00e7\u00f5es nas redes sociais como ferramenta para identificar oportunidades, enquanto Flor\u00eancia Ferrari destacou que sustentabilidade, mudan\u00e7as clim\u00e1ticas, feminismo e intelig\u00eancia artificial continuar\u00e3o entre os principais temas do setor.<\/p>\n<p>Ainda no dia 21, a mesa \u201cDo Original \u00e0 Publica\u00e7\u00e3o\u201d trouxe Diana Passy, curadora da Arena Cultural da Bienal Internacional do Livro de SP, que abordou o fortalecimento de autores nacionais. Para ela, comunidades liter\u00e1rias representam um diferencial competitivo, j\u00e1 que funcionam como ecossistemas que aproximam autores e leitores. Mais do que apostar em grandes influenciadores, o segredo est\u00e1 em entender e dialogar com a comunidade certa. \u00c0 tarde, o debate voltou-se \u00e0s pol\u00edticas p\u00fablicas com a mesa \u201cPNLL: Desafios e Perspectivas para o Setor Editorial\u201d, que contou com Hubert Alqu\u00e9res (CBL), Mara Cortez (Cortez Editora e Livraria), Lu\u00eds Antonio Torelli (Trilha Educacional Editora) e Sevani Matos (presidente da CBL). Alqu\u00e9res ressaltou a necessidade de linhas de cr\u00e9dito e editais de fomento espec\u00edficos para as livrarias, a exemplo do que acontece com os teatros. Torelli defendeu a aprova\u00e7\u00e3o da Lei Cortez e a transforma\u00e7\u00e3o do PNLL em pol\u00edtica de Estado, lembrando que o mercado n\u00e3o pode ignorar a perda de mais de 4 milh\u00f5es de leitores. Sevani Matos refor\u00e7ou a responsabilidade das editoras no abastecimento de programas de leitura, defendendo a bibliodiversidade como essencial para garantir diversidade e qualidade ao p\u00fablico, enquanto Mara Cortez destacou que os incentivos beneficiam n\u00e3o apenas as livrarias, mas toda a cultura nacional.<\/p>\n<p>Na mesa \u201cIdeias que Sa\u00edram da Gaveta: Iniciativas que Transformaram Cat\u00e1logos, Leitores e Resultados\u201d, mediada por Andr\u00e9 Lu\u00eds Silvestre Cafu (Global Editora), Monica Carvalho (Livraria da Tarde) ressaltou a for\u00e7a das parcerias, como a feira realizada na Rua Rocha, em parceria com a Livraria Simples. Ramir Severiano (Vitrola) compartilhou os desafios de ampliar a presen\u00e7a do livro em espa\u00e7os n\u00e3o convencionais, como supermercados, lembrando que al\u00e9m de paix\u00e3o \u00e9 preciso rentabilidade. Cecilia Arbolave (Lote 42, Banca Tatu\u00ed e Sala Tatu\u00ed) apontou como obst\u00e1culos podem se transformar em oportunidades e destacou o papel da impress\u00e3o sob demanda, inexistente h\u00e1 dez anos, na democratiza\u00e7\u00e3o das publica\u00e7\u00f5es. J\u00e1 Wellington Rehder (Gr\u00e1fica Viena) defendeu a busca constante por inova\u00e7\u00e3o como forma de ajudar os clientes a produzirem livros melhores com menos recursos, mantendo qualidade e viabilidade econ\u00f4mica.<\/p>\n<p>O \u00faltimo dia do encontro abriu com a mesa \u201cEditando o Futuro: Selos, Estrat\u00e9gias e Novos P\u00fablicos\u201d, com Rafaella Machado (Galera Record e Verus Editora) e media\u00e7\u00e3o de Maria Fernanda Rodrigues (O Estado de S. Paulo). Rafaella destacou o protagonismo do p\u00fablico jovem adulto, que vai al\u00e9m da faixa et\u00e1ria, e refor\u00e7ou a import\u00e2ncia das livrarias como espa\u00e7os de encontro e experi\u00eancia, oferecendo algo que o ambiente online n\u00e3o \u00e9 capaz de replicar. A programa\u00e7\u00e3o encerrou-se com debates sobre uso de dados no mercado editorial, responsabilidade ESG, leitores digitais e aspectos legais da intelig\u00eancia artificial, reunindo nomes como Nelson Naspitz (Sextante), Daniel Rodrigues (Livraria Leitura), Marcus Nakagawa (Abraps), Thereza Castro (Citadel Grupo Editorial), Luciano Monteiro (CBL), Adriana Alc\u00e2ntara (Audible) e Maria Luiza de Freitas Valle Egea (Freitas Valle Egea Advogados Associados).<\/p>","protected":false},"excerpt":{"rendered":"<p>Com 23 mesas e mais de 300 participantes, evento se consolida como f\u00f3rum estrat\u00e9gico para debater a cadeia do livro no Brasil &nbsp; Com a participa\u00e7\u00e3o de mais de 300 profissionais do setor, 9 expositores, 18 patrocinadores, 23 mesas e um total de 67 palestrantes, incluindo dois convidados internacionais, a 4\u00aa edi\u00e7\u00e3o do Encontro de [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":116068,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-116067","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nao-categorizado"],"acf":[],"_links":{"self":[{"href":"https:\/\/cbltestlnx.azurewebsites.net\/en\/wp-json\/wp\/v2\/posts\/116067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbltestlnx.azurewebsites.net\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbltestlnx.azurewebsites.net\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbltestlnx.azurewebsites.net\/en\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/cbltestlnx.azurewebsites.net\/en\/wp-json\/wp\/v2\/comments?post=116067"}],"version-history":[{"count":1,"href":"https:\/\/cbltestlnx.azurewebsites.net\/en\/wp-json\/wp\/v2\/posts\/116067\/revisions"}],"predecessor-version":[{"id":116069,"href":"https:\/\/cbltestlnx.azurewebsites.net\/en\/wp-json\/wp\/v2\/posts\/116067\/revisions\/116069"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cbltestlnx.azurewebsites.net\/en\/wp-json\/wp\/v2\/media\/116068"}],"wp:attachment":[{"href":"https:\/\/cbltestlnx.azurewebsites.net\/en\/wp-json\/wp\/v2\/media?parent=116067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbltestlnx.azurewebsites.net\/en\/wp-json\/wp\/v2\/categories?post=116067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbltestlnx.azurewebsites.net\/en\/wp-json\/wp\/v2\/tags?post=116067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}